{"id":1139,"count":74,"description":"","link":"https:\/\/enlineabarcelona.com\/ca\/.\/mobiliario\/sillas\/","name":"Sillas","slug":"sillas","taxonomy":"product_cat","parent":298,"meta":[],"menu_order":0,"acf":{"titulo_seo":"","preguntas_seo":null},"_links":{"self":[{"href":"https:\/\/enlineabarcelona.com\/ca\/wp-json\/wp\/v2\/product_cat\/1139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enlineabarcelona.com\/ca\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/enlineabarcelona.com\/ca\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/enlineabarcelona.com\/ca\/wp-json\/wp\/v2\/product_cat\/298"}],"wp:post_type":[{"href":"https:\/\/enlineabarcelona.com\/ca\/wp-json\/wp\/v2\/product?product_cat=1139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}