{"id":1147,"count":77,"description":"","link":"https:\/\/enlineabarcelona.com\/ca\/.\/mobiliario\/sofas\/","name":"Sof\u00e1s","slug":"sofas","taxonomy":"product_cat","parent":298,"meta":[],"menu_order":0,"acf":{"titulo_seo":"","preguntas_seo":null},"_links":{"self":[{"href":"https:\/\/enlineabarcelona.com\/ca\/wp-json\/wp\/v2\/product_cat\/1147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enlineabarcelona.com\/ca\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/enlineabarcelona.com\/ca\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/enlineabarcelona.com\/ca\/wp-json\/wp\/v2\/product_cat\/298"}],"wp:post_type":[{"href":"https:\/\/enlineabarcelona.com\/ca\/wp-json\/wp\/v2\/product?product_cat=1147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}